{"id":2093,"date":"2025-10-14T15:16:27","date_gmt":"2025-10-14T13:16:27","guid":{"rendered":"https:\/\/www.hotelcasajusta.com\/suites\/"},"modified":"2026-02-11T12:14:04","modified_gmt":"2026-02-11T10:14:04","slug":"suites","status":"publish","type":"page","link":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/","title":{"rendered":"Landelijk huis Tenerife Noord"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_94be0cb5 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default reversed stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_850593c5\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Ons landelijke hotel in<br \/>\nNoord-Tenerife&#8221; font_container=&#8221;tag:h1|text_align:left&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%223rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%223rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_0bbc651a\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Casa Justa is meer dan een hotel, het is een <strong>landelijk huis in Noord-Tenerife<\/strong> met geschiedenis. Dit iconische hotel in Tegueste, dat meer dan 225 jaar oud is, heeft de essentie van de traditionele Canarische architectuur behouden: houten plafonds, stenen muren en patio&#8217;s vol licht. Elke hoek is met zorg gerestaureerd, met respect voor het oorspronkelijke karakter en gecombineerd met de gemakken van nu. Hier staat de tijd stil en wordt rust de echte hoofdrolspeler.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_2 us_custom_703b2333\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_1\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_557_235883699.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_557_235883699.jpg\" width=\"1024\" height=\"683\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:683}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_528e4157 experiencia-unica height_auto full_height valign_center width_full\" id=\"zonasexteriores\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_9a607f21\"><div class=\"wpb_wrapper\"><div class=\"w-image imgserv align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394275.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394275.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394275-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_442fece4\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Landelijk huis in Noord-Tenerife<br \/>\ntussen wijngaarden en bergen&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-10rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-10rem%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%221rem%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%221rem%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_5f441a03\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">De buitenruimtes van Casa Justa zijn de levende ziel van ons <strong>landelijk hotel in Tenerife<\/strong>. Tussen stenen muren en houten patio&#8217;s opent het huis zich naar het landschap van Tegueste en biedt het hoekjes waar de stilte, de bries en de geur van vochtige aarde uitnodigen tot ontspanning. Hier staat de tijd stil: ontbijten in de openlucht, lezen in de schaduw van een eeuwenoude wijnstok, gesprekken naast de oude landbouwwagen of een zonsondergang met uitzicht op het ravijn en de wijngaarden. Alles is ontworpen om het rustige ritme van Noord-Tenerife te beleven.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_aacd3097 height_medium\" id=\"zonascasa\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_cf3d7369\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row us_custom_f97e3b99 via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_f2eec366\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Gebieden van ons landelijke hotel&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner us_custom_ed56d00e\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"#zonasexteriores\" class=\"w-iconbox-link\" aria-label=\"Buitenzones\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/ChatGPT-Image-16-oct-2025-18_56_55.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/ChatGPT-Image-16-oct-2025-18_56_55.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/ChatGPT-Image-16-oct-2025-18_56_55-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/ChatGPT-Image-16-oct-2025-18_56_55-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#zonasexteriores\" class=\"w-iconbox-link\" aria-label=\"Buitenzones\">Buitenzones<\/a><\/p><\/div><\/div><\/div><\/div><a href=\"#zonasexteriores\" class=\"vc_column-link smooth-scroll\" aria-label=\"Link\"><\/a><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_eb849559\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_a0bc2650 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"#zonahall\" class=\"w-iconbox-link\" aria-label=\"Hall\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/0b76b7ae-984c-488c-a39d-afe2a6e27548.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/0b76b7ae-984c-488c-a39d-afe2a6e27548.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/0b76b7ae-984c-488c-a39d-afe2a6e27548-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/0b76b7ae-984c-488c-a39d-afe2a6e27548-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"#zonahall\" class=\"w-iconbox-link\" aria-label=\"Hall\">Hall<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_6dc8e970\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_a0bc2650 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-1-la-vina\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Vi\u00f1a\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/dbb16f0a-1a30-49be-bff5-312b72cc9da9.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/dbb16f0a-1a30-49be-bff5-312b72cc9da9.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/dbb16f0a-1a30-49be-bff5-312b72cc9da9-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/dbb16f0a-1a30-49be-bff5-312b72cc9da9-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-1-la-vina\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Vi\u00f1a\">Kamer Vi\u00f1a<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7d09ab0f\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-2-los-alisios\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Patio\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/9e43f595-c2f0-49c0-bfeb-07a90cbec77b.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/9e43f595-c2f0-49c0-bfeb-07a90cbec77b.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/9e43f595-c2f0-49c0-bfeb-07a90cbec77b-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/9e43f595-c2f0-49c0-bfeb-07a90cbec77b-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-2-los-alisios\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Patio\">Kamer Patio<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7d09ab0f\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-3-la-laja\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Laja\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/60f91778-8cf0-4267-a843-bf67f2e8658d.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/60f91778-8cf0-4267-a843-bf67f2e8658d.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/60f91778-8cf0-4267-a843-bf67f2e8658d-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/60f91778-8cf0-4267-a843-bf67f2e8658d-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-3-la-laja\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Laja\">Kamer Laja<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7d09ab0f\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer La Sabina\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/fc746d6f-5822-4ca2-92c2-5e1ff148d3c2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/fc746d6f-5822-4ca2-92c2-5e1ff148d3c2.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/fc746d6f-5822-4ca2-92c2-5e1ff148d3c2-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/fc746d6f-5822-4ca2-92c2-5e1ff148d3c2-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer La Sabina\">Kamer La Sabina<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7d09ab0f\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Drago\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/6b32aa12-edb2-4920-93e2-f43c52dab666.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/6b32aa12-edb2-4920-93e2-f43c52dab666.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/6b32aa12-edb2-4920-93e2-f43c52dab666-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/6b32aa12-edb2-4920-93e2-f43c52dab666-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Drago\">Kamer Drago<\/a><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7d09ab0f\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_f7182f18 servicios iconpos_left style_default color_primary align_center no_text icontype_img\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Laurel\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/be0e8269-c081-4418-bbf2-e08c4e3965ae.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/be0e8269-c081-4418-bbf2-e08c4e3965ae.png 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/be0e8269-c081-4418-bbf2-e08c4e3965ae-300x300.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/be0e8269-c081-4418-bbf2-e08c4e3965ae-150x150.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/a><div class=\"w-iconbox-meta\"><p class=\"w-iconbox-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel-2\/\" class=\"w-iconbox-link\" aria-label=\"Kamer Laurel\">Kamer Laurel<\/a><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_5bfb64f5 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default reversed stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_f4c1bc39\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;De Canarische Patio&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_9e56d61e\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Het hart van het huis behoudt de authenticiteit van een 19e-eeuwse woning. De stenen vloer en de vulkanische stenen muren contrasteren met de bloemen en de warmte van het hout. Hier herinneren de oude landbouwwagen en de traditionele objecten ons aan de levende geschiedenis van het landgoed. Het is de perfecte plek om buiten te ontbijten, te genieten van een rustige lezing of gewoon te genieten van de rust van de omgeving.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_5\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883703-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"620\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg\"><span data-alt=\"Landelijk huis in Noord-Tenerife\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"651\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_553_235883695.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883704-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"972\" data-rsh=\"768\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394290.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883703-1.jpg\" width=\"1024\" height=\"683\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:683}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_4b9bf007 experiencia-unica height_auto full_height valign_center width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_67d4a961\"><div class=\"wpb_wrapper\"><div class=\"w-image imgserv align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_baa8ba02\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Het terras van de<br \/>\nPorche&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-5rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_f0033a5d\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Onder het houten dak biedt het hoofdterras een gezellige sfeer met tafels en stoelen waar u onvergetelijke momenten kunt delen. Vanuit deze ruimte kunt u de bergen en wijngaarden van Tegueste aanschouwen, terwijl de bries en het geluid van de natuur een sfeer van sereniteit cre\u00ebren.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1ce7bf30 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default reversed stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_f4c1bc39\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;De tuin en<br \/>\nChill-Out Zone&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_798be4a1\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Tussen palmbomen en inheemse planten wordt de tuin een oase van welzijn. Deze ruimte is ingericht met handgemaakte houten banken en tafels en nodigt uit om te rusten, te praten of de avond te zien vallen terwijl de zon de hellingen van de vallei verlicht. De chill-out zone, met houten banken en gekleurde kussens, biedt een intiem hoekje om te ontspannen en te genieten van de stilte.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_7\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883684.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883703-1-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"608\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_549_235883676.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"696\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394252.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"687\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394261-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"708\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394266.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394307.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883684.jpg\" width=\"1024\" height=\"683\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:683}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row experiencia-unica height_auto full_height valign_center width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_7f577831\"><div class=\"wpb_wrapper\"><div class=\"w-image imgserv align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1003\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883689-1.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883689-1.png 1003w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883689-1-300x204.png 300w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_84804d30\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Zwembad met uitzicht<br \/>\nop de vallei&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-5rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_c4106802\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Het buitenzwembad is een van de meest bijzondere plekken van Casa Justa. Omgeven door de natuur en met een panoramisch uitzicht op de bergen van Anaga, kunt u genieten van een ontspannen duik in een unieke omgeving. De houten ligstoelen en het natuurlijke gras cre\u00ebren de ideale omgeving om te zonnebaden of gewoon het landschap te aanschouwen.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_bf1ded0b height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default reversed stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_542463e4\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Barbecue en<br \/>\nBodega in de openlucht&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_cd643641\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">De wijntraditie van Tegueste is hier ook voelbaar. De buitenbarbecue, vergezeld van gerecyclede vaten en rustieke tafels, nodigt uit om te genieten van maaltijden in de openlucht of ge\u00efmproviseerde proeverijen onder de sterrenhemel. Een ruimte ontworpen om te delen, waar het aroma van wijn en brandhout zich vermengt met de zuivere lucht van Noord-Tenerife<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_3\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394275.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"690\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394268-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394272.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394275.jpg\" width=\"1024\" height=\"683\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:683}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row experiencia-unica height_auto full_height valign_center width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_5e68f93d\"><div class=\"wpb_wrapper\"><div class=\"w-image imgserv align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"687\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280-300x201.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_7be2ff44\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Het houten huisje en<br \/>\nHoekjes met charme&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-3rem%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_c4fa6a29\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Tussen de vegetatie is een klein houten huisje verborgen: een gezellig toevluchtsoord met banken en rustieke decoratie, perfect om te ontspannen of te kletsen met z&#8217;n twee\u00ebn. Rondom herinneren oude elementen van vulkanisch gesteente, kruiken en aangelegde paden ons aan het agrarische verleden van het huis.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1ce7bf30 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default reversed stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_261413b7\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Natuur en traditie&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_17274f32\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Elke buitenhoek van Casa Justa bewaart een verhaal: van de keramische inscriptie die de oprichting in 1800 aankondigt tot de rode stenen muren die nog steeds de ziel van de traditionele Canarische architectuur bewaren. Hier is elk detail ontworpen om vrede, authenticiteit en verbinding met de omgeving over te brengen.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_4\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"535\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_533_279394327.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/235883684-1.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"707\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394299.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1024\" data-rsh=\"683\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394305.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_533_279394327.jpg\" width=\"1024\" height=\"535\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:535}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_e4358bc3 height_auto full_height valign_center width_full\" id=\"zonahall\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_3e3c9574\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_083c564a imghall align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1011\" height=\"689\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_545_235883714-1.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_545_235883714-1.png 1011w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_545_235883714-1-300x204.png 300w\" sizes=\"auto, (max-width: 1011px) 100vw, 1011px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_05112062\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Hal&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%222.2rem%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-5rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_05b69e30\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Zodra de bezoeker de hoofdingang oversteekt, merkt hij dat Casa Justa geen gewoon hotel is: het is een huis met een ziel. De hal heeft de originele charme van zijn meer dan twee eeuwen geschiedenis behouden, met stenen muren, houten balken en details die het landelijke verleden van Tegueste vertellen. Hier worden oude landbouwwerktuigen, olielampen, zadels en traditionele gebruiksvoorwerpen vermengd met elementen van hedendaags design, waardoor een sfeer ontstaat die geschiedenis en comfort combineert. Elk stuk heeft een doel: de gast verbinden met de levende herinnering aan het eiland.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_2 us_custom_03e155f4\" href=\"#zonascasa\"><span class=\"w-btn-label\">BEKIJK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row testimonios height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Beoordelingen van onze gasten&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%7D&#8221;]<div class=\"w-html\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-content-align-center\" data-no-translation=\"true\" data-layout-id=\"36\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKVEV9RoCRcb-i5sIH74ndfPbdoBpv296b2wzvrn8Up-Lj0CA=w64-h64-c-rp-mo-br100\" alt=\"Jesus Mar\u00eda Mach\u00edn profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jesus Mar\u00eda Mach\u00edn <\/div> <div class=\"ti-date\">03\/12\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->casa Do\u00f1aJusta, tremendo y excelente alojamiento rural,,!,? Casa con todas las comodidades a d\u00eda de hoy, unas paredes cargadas de historia , exquisita restauraci\u00f3n y adaptaci\u00f3n a los nuevos tiempos y su funcionalidad como hotel rural,..buen\u00edsima energ\u00eda en todo el entorno, ideal para el descanso . Andando muy muy cerca, el centro  del pueblo de Tegueste, donde est\u00e1 ubicada,.\nTegueste, peque\u00f1o gran pueblo al norte de Tenerife, a mi modo de ver desconocido e infravalorado por muchos..que lo tiene todo., comercios de todo tipo,  buen\u00edsima y variada hosteler\u00eda , mercadillo agr\u00edcola los fines de semana, con variedad de productos locales de cercan\u00eda y gran calidad , menci\u00f3n especial a las carnicer\u00edas del pueblo, con la hist\u00f3rica Carnicer\u00eda Florencio, y el maestro Tito al frente de case cien a\u00f1os de tradici\u00f3n familiar ..las mejores carnes del pa\u00eds (Canarias ) est\u00e1n aqu\u00ed..y muy buenos precios.\nMultitud de interesantes rutas para caminar desde el propio pueblo o desde puntos cercanos \u2026parques rurales \u2026 costa..\nAdem\u00e1s\u2026.a tan s\u00f3lo 15 minutos de la Laguna hist\u00f3rica,, lo cual  abre el abanico  de posibilidades ,de ocio gastron\u00f3micas,comerciales y culturales \u2026de forma infinita.\nEn fin que me gusta Tegueste ,, y que en esta casa estamos a gust\u00edsimo  cada vez que vamos .<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKpJMXA1WvGG43Pqb7cbP5lVN7GeO6JEd-tGbjBvA5IlDD0lc8=w64-h64-c-rp-mo-br100\" alt=\"Eztizen Gonz\u00e1lez Sagarduy profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Eztizen Gonz\u00e1lez Sagarduy <\/div> <div class=\"ti-date\">19\/09\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Estuvimos en Casa Justa hace unas semanas y la experiencia fue excelente. Es un espacio muy tranquilo y acogedor,  perfecto para desconectar y descansar. Desde el proceso de reserva hasta la estancia, la atenci\u00f3n de Peli fue inmejorable. Sin duda, un lugar muy recomendable.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV21hPYO1kQ8kxMkuDaO3t7u8mP0i5LyVDJttCrrq2ei0zWDQLhmg=w64-h64-c-rp-mo-ba4-br100\" alt=\"Carlos A. Armas Su\u00e1rez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Carlos A. Armas Su\u00e1rez <\/div> <div class=\"ti-date\">22\/08\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Buen sitio para hacer una escapada de fin de semana o hacer unas vacaciones. Sitio super tranquilo, no s\u00e9 oye nada y te despiertan los p\u00e1jaros por la ma\u00f1ana.. De diez..<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXZgnFWqWOz_my8AIxcj4EIsJ69uIK_OyMEVcjReo1pMWX-sPf9=w64-h64-c-rp-mo-ba3-br100\" alt=\"Simon Cooper profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Simon Cooper <\/div> <div class=\"ti-date\">29\/01\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Wonderful flat in a gorgeous house with grounds. Superb bed and facilities plus lovely sitting out area with pool and views. Quiet location  short walk from the centre of town. Would love to come and stay again<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVZ7KPiAN7kbMo0-Z5QryKwP_nB3439z-eknT7iN5iaQu8Q7vA=w64-h64-c-rp-mo-ba4-br100\" alt=\"Pavel Konrad profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Pavel Konrad <\/div> <div class=\"ti-date\">19\/01\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Einfach, aber zauberhaft.\nGute Restaurants in der N\u00e4he.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLD0WF902Bok-Ja5GGl6fNhP-Q4X054vDBzXMm6JdnuG5Ow0g=w64-h64-c-rp-mo-ba4-br100\" alt=\"emma Cabello profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> emma Cabello <\/div> <div class=\"ti-date\">11\/10\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Un gran lugar, tranquilo, buen trato, recomendado<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVhQgriKNd1ny4vgWlapLKbDtxAQTUvH5IaozZVnnRrLUSt6B04=w64-h64-c-rp-mo-ba2-br100\" alt=\"Josef Schartner profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Josef Schartner <\/div> <div class=\"ti-date\">18\/05\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Kleine, nette Anlage mit super m\u00f6glichkeiten f\u00fcr die Freizeit. Unsere Wohnung war au\u00dfergew\u00f6hnlich eingerichtet und sehr sch\u00f6n und gro\u00df. Wenn, dann wieder hier. Tugueste hat auch gut gefallen, waren 6 N\u00e4chte dort.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXHzAvL01Sgd-Bcuuj43wkWgfzc6ru2Vk3RC5WGhBwfuXCCQJs=w64-h64-c-rp-mo-ba4-br100\" alt=\"Louise Bankhead profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Louise Bankhead <\/div> <div class=\"ti-date\">20\/04\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Beautiful place with a lot of character. Very well situated.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL1X3h9s6MKRiWTxDepUTqUNkOaIuFXWdhpS33ovQDM2Y76mw=w64-h64-c-rp-mo-br100\" alt=\"Juan Antonio profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Juan Antonio <\/div> <div class=\"ti-date\">07\/04\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Sitio muy bonito y muy limpio. Trato agradable de todos,  Peli, Marisol y Pedro. Gracias, volveremos pronto.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"1\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVFcCg6Q6dBhT9g5VjRFLiU62GGGhtOQ49BzCK5xX_ns_kgmFwWxg=w64-h64-c-rp-mo-br100\" alt=\"Nuria Guti\u00e9rrez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Nuria Guti\u00e9rrez <\/div> <div class=\"ti-date\">17\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>    <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/trustindex-google-widget.css?1765895602\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_24941e40 height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Diensten van ons Landelijk Hotel in Noord-Tenerife&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-top%22%3A%221rem%22%7D%7D&#8221;]<div class=\"g-cols wpb_row us_custom_6d149020 via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_78203f0a cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/1.png\" class=\"attachment-full size-full\" alt=\"wifi\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Gratis wifi in<br \/>\nalle ruimtes<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/2.png\" class=\"attachment-full size-full\" alt=\"limpieza\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Schoonmaak<br \/>\nservice inbegrepen<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/3.png\" class=\"attachment-full size-full\" alt=\"piscina\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Zwembad<br \/>\nin de openlucht<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4.png\" class=\"attachment-full size-full\" alt=\"info\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Toerisme en routes<br \/>\naanbevolen<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/5.png\" class=\"attachment-full size-full\" alt=\"parking\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Priv\u00e9parkeerplaats op het terrein<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_8233be8a height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Afbeeldingen van ons iconische landelijk huis in Tenerife&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"w-separator size_small\"><\/div><div class=\"w-gallery fit_cover type_metro_2 action_popup_image ratio_1x1 count_30\" style=\"--columns:4;--items-gap:10px;\"><div class=\"w-gallery-list\"><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394250.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394250.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394250-300x217.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"279394250\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394250.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"687\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280-300x201.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"imgi_501_279394280\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_501_279394280.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394305.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394305.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394305-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"279394305\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394305.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_186_279394299.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_186_279394299.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_186_279394299-300x207.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"imgi_186_279394299\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_186_279394299.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"279394313\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/279394313.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_529_279394320.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_529_279394320.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_529_279394320-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"imgi_529_279394320\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_529_279394320.jpg\"><\/a><\/div><\/div><div class=\"w-gallery-loadmore\" style=\"--btn-indent:1.5em\"><button  class=\"w-btn us-btn-style_4\"><span class=\"w-btn-label\">Laad meer<\/span><\/button><div class=\"g-preloader type_1\"><div><\/div><\/div><\/div><div class=\"w-gallery-json hidden\"  onclick='return {&quot;action&quot;:&quot;us_ajax_gallery&quot;,&quot;template_vars&quot;:{&quot;ids&quot;:[2131,2125,2128,2133,2114,2134,2116,2119,2097,2132,2108,2121,1970,2107,2127,2113,2126,2137,2118,2109,2129,2136,2112,2130,2122,2135,2120,2115,2124,2111],&quot;img_size&quot;:&quot;large&quot;,&quot;items_click_action&quot;:&quot;popup_image&quot;,&quot;items_link&quot;:&quot;{\\&quot;url\\&quot;:\\&quot;\\&quot;}&quot;,&quot;items_title&quot;:0,&quot;max_num_pages&quot;:5,&quot;quantity&quot;:&quot;6&quot;,&quot;pagination&quot;:&quot;load_on_btn&quot;}}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row faq-section height_large width_custom\" style=\"--site-content-width:1000px;\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Veelgestelde vragen over ons Hotel Rural in Noord-Tenerife&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%220%22%7D%7D&#8221;]<div class=\"w-tabs us_custom_71d3e3d1 style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"laeb\"><button class=\"w-tabs-section-header\" aria-controls=\"content-laeb\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke soorten verblijven biedt Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content us_custom_25ce5a41\" id=\"content-laeb\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Wij bieden ruime en gezellige kamers in een traditionele Canarische stijl, uitgerust met alle nodige voorzieningen voor een ontspannen verblijf. We hebben tweepersoonskamers, familiekamers en suites met uitzicht op de natuurlijke omgeving.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"vc2f\"><button class=\"w-tabs-section-header\" aria-controls=\"content-vc2f\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is het toegestaan om te koken in ons landelijk huis in Noord-Tenerife?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-vc2f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Sommige van onze kamers en appartementen hebben een keuken die is uitgerust voor priv\u00e9gebruik. Als er geen keuken aanwezig is, bieden we toegang tot gemeenschappelijke ruimtes waar u basisvoedsel kunt bereiden.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"hd42\"><button class=\"w-tabs-section-header\" aria-controls=\"content-hd42\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is Casa Do\u00f1a Justa geschikt voor gezinnen?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-hd42\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja. Onze accommodatie is perfect voor gezinnen die op zoek zijn naar rust en natuur. We hebben familiekamers, grote buitenruimtes en activiteiten in de buurt die ideaal zijn voor kinderen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"fe58\"><button class=\"w-tabs-section-header\" aria-controls=\"content-fe58\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Zijn huisdieren toegestaan?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-fe58\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Nee, het spijt ons, huisdieren zijn niet toegestaan in onze faciliteiten. Dit beleid helpt ons om een rustige en geschikte omgeving voor al onze gasten te behouden.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"sf67\"><button class=\"w-tabs-section-header\" aria-controls=\"content-sf67\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Wat is het in- en uitcheckbeleid?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-sf67\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Inchecken kan vanaf 15:00 uur en uitchecken tot 11:00 uur. Als u andere tijden nodig heeft, neem dan contact met ons op en we zullen ons best doen om ons aan te passen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"i088\"><button class=\"w-tabs-section-header\" aria-controls=\"content-i088\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is er parkeergelegenheid beschikbaar?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-i088\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja, we hebben gratis priv\u00e9parkeergelegenheid voor gasten, afhankelijk van beschikbaarheid. Het is ook mogelijk om gemakkelijk te parkeren in de directe omgeving van het etablissement.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"q208\"><button class=\"w-tabs-section-header\" aria-controls=\"content-q208\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke extra diensten biedt Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-q208\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Onze diensten omvatten:<\/p>\n<p>Ontbijt met lokale producten<\/p>\n<p>Gratis wifi in alle faciliteiten<\/p>\n<p>Terras en tuinen<\/p>\n<p>Schoonmaakservice<\/p>\n<p>Toeristische informatie en activiteitenbeheer<\/p>\n<p>Transfers op aanvraag (tegen extra kosten)<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"e387\"><button class=\"w-tabs-section-header\" aria-controls=\"content-e387\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke activiteiten zijn er in de buurt te doen?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-e387\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>De locatie is ideaal om te genieten van de natuur en cultuur van Tenerife. In de buurt kunt u:<\/p>\n<p>Wandelroutes<\/p>\n<p>Sterren kijken<\/p>\n<p>Avontuurlijke sporten<\/p>\n<p>Stranden en natuurlijke zwembaden<\/p>\n<p>Bezoeken aan traditionele dorpen en ambachtelijke markten<\/p>\n<p>Bezoeken aan lokale wijnkelders<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"u49f\"><button class=\"w-tabs-section-header\" aria-controls=\"content-u49f\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Hoe kom ik bij Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-u49f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>We zijn gevestigd in een landelijk gebied dat goed verbonden is met de belangrijkste wegen van het eiland. Na de reservering ontvangt u gedetailleerde instructies en GPS-co\u00f6rdinaten. We kunnen u ook helpen bij het organiseren van transfers vanaf de luchthaven.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"t5b4\"><button class=\"w-tabs-section-header\" aria-controls=\"content-t5b4\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Kunnen reserveringen rechtstreeks op de website worden gemaakt?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-t5b4\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja, u kunt gemakkelijk en met de beste prijsgarantie reserveren via onze offici\u00eble website. Het proces is eenvoudig, veilig en u kunt de beschikbaarheid in realtime raadplegen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_057801f8 contacto height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Neem contact met<br \/>\nons op&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%220%22%7D%7D&#8221;]<div class=\"w-iconbox iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"19\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/1a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><a href=\"https:\/\/www.google.com\/maps\/place\/Hotel+Casa+Justa+%7C+Hotel+Rural+Tenerife\/@28.5253872,-16.3397147,955m\/data=!3m2!1e3!4b1!4m9!3m8!1s0xc41cfcc80153085:0xdd81c2026ee9182b!5m2!4m1!1i2!8m2!3d28.5253825!4d-16.3371398!16s%2Fg%2F11g0qs9rzt?authuser=0&amp;entry=ttu&amp;g_ep=EgoyMDI2MDEwNy4wIKXMDSoASAFQAw%3D%3D\">C. Astrof\u00edsico Pedro Alvarez Mart\u00edn, 24, 38280 Tegueste, Santa Cruz de Tenerife<\/a><\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"19\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/2a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><a href=\"tel:+34626821926\">+34 626 821 926<\/a><\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"17\" height=\"13\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/3a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><a href=\"mailto:info@hotelcasajusta.com\">info@hotelcasajusta.com<\/a><\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p>Openingstijden:<br \/>\nMaandag tot zondag: 09:00 \u2013 20:00<\/p>\n<\/div><\/div><\/div><div class=\"w-image us_custom_703b2333 align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"671\" height=\"228\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007.png\" class=\"attachment-full size-full\" alt=\"map\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007.png 671w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007-300x102.png 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2692-o1\" lang=\"nl-NL\" dir=\"ltr\" data-wpcf7-id=\"2692\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/2093#wpcf7-f2692-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2692\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"nl_NL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2692-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<label for=\"nombre\"> Uw naam *\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"nombre\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span> <\/label>\n\n<label for=\"email\"> Uw e-mailadres *\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label>\n\n<label for=\"telefono\"> Uw telefoonnummer *\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" id=\"telefono\" autocomplete=\"tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span> <\/label>\n\n<label for=\"mensaje\"> Uw bericht\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" id=\"mensaje\" aria-invalid=\"false\" name=\"mensaje\"><\/textarea><\/span> <\/label>\n\n<label for=\"aceptacion\"><span class=\"wpcf7-form-control-wrap\" data-name=\"aceptacion\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"aceptacion\" value=\"1\" id=\"aceptacion\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ik heb het <a rel=\"nofollow\" target=\"_blank\" href=\"\/politica-de-privacidad\/\">privacybeleid<\/a> gelezen en ga ermee akkoord.<\/label>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"form-contact\" type=\"submit\" value=\"Verzenden\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"Ons landelijke hotel in Noord-Tenerife\" font_container=\"tag:h1|text_align:left\" google_fonts=\"font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal\" tag_name=\"h2\" css=\"%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%223rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%223rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D\"]Casa Justa is meer dan een hotel, het is een landelijk huis in Noord-Tenerife met geschiedenis. Dit iconische hotel in Tegueste, dat meer dan 225 jaar oud is, heeft de essentie van de traditionele Canarische architectuur behouden: houten plafonds, stenen muren en patio&#8217;s vol licht. Elke...","protected":false},"author":1,"featured_media":2112,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2093","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa<\/title>\n<meta name=\"description\" content=\"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa\" \/>\n<meta property=\"og:description\" content=\"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/\" \/>\n<meta property=\"og:site_name\" content=\"hotelcasajusta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T10:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/\",\"name\":\"Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/imgi_2_235883669.jpg\",\"datePublished\":\"2025-10-14T13:16:27+00:00\",\"dateModified\":\"2026-02-11T10:14:04+00:00\",\"description\":\"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/imgi_2_235883669.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/imgi_2_235883669.jpg\",\"width\":1024,\"height\":620,\"caption\":\"Landelijk huis in Noord-Tenerife\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/suites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/?page_id=1887\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landelijk huis Tenerife Noord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/\",\"name\":\"hotelcasajusta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa","description":"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/","og_locale":"nl_NL","og_type":"article","og_title":"Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa","og_description":"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.","og_url":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/","og_site_name":"hotelcasajusta","article_modified_time":"2026-02-11T10:14:04+00:00","og_image":[{"width":1024,"height":620,"url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"8 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/","url":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/","name":"Landelijk hotel in het noorden van Tenerife | Hotel Casa Justa","isPartOf":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/#primaryimage"},"image":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg","datePublished":"2025-10-14T13:16:27+00:00","dateModified":"2026-02-11T10:14:04+00:00","description":"Hotel Casa Justa, uw landelijke hotel in het noorden van Tenerife, wij bieden rust, natuur en Canarische gastvrijheid voor een onvergetelijk verblijf.","breadcrumb":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelcasajusta.com\/nl\/suites\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/#primaryimage","url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg","contentUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/imgi_2_235883669.jpg","width":1024,"height":620,"caption":"Landelijk huis in Noord-Tenerife"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelcasajusta.com\/nl\/suites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hotelcasajusta.com\/nl\/?page_id=1887"},{"@type":"ListItem","position":2,"name":"Landelijk huis Tenerife Noord"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelcasajusta.com\/nl\/#website","url":"https:\/\/www.hotelcasajusta.com\/nl\/","name":"hotelcasajusta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelcasajusta.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/2093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/comments?post=2093"}],"version-history":[{"count":29,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/2093\/revisions"}],"predecessor-version":[{"id":3279,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/2093\/revisions\/3279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/media\/2112"}],"wp:attachment":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/media?parent=2093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}