{"id":1887,"date":"2022-09-30T10:24:42","date_gmt":"2022-09-30T08:24:42","guid":{"rendered":"https:\/\/www.hotelcasajusta.com\/hotel-casa-justa\/"},"modified":"2025-12-30T12:47:02","modified_gmt":"2025-12-30T10:47:02","slug":"hotel-casa-justa","status":"publish","type":"page","link":"https:\/\/www.hotelcasajusta.com\/nl\/","title":{"rendered":"Hotel Casa Justa"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_94be0cb5 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-content-carousel items_1 us_custom_edb423b1 carousel-video\"><div class=\"owl-carousel valign_stretch dotstyle_circle navstyle_6 navpos_inside owl-responsive-2000 with_arrows\" style=\"--items-gap:30px;--transition-duration:350ms;--arrows-size:1.5rem;\" onclick=\"return {&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Previous&quot;,&quot;next&quot;:&quot;Volgende&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:0,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:30,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;651&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:true,&quot;stagePadding&quot;:0}}}\"><div class=\"w-video videocabecera align_none ratio_21x9\"><div class=\"w-video-h\"><video  preload=\"metadata\" playsinline autoplay loop muted><source type=\"video\/mp4\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/Video-Home.mp4\" \/><\/video><\/div><\/div><div class=\"w-image has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:42.8571%\"><\/div><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/CABECERA-1024x538.png\" class=\"attachment-large size-large\" alt=\"CABECERA\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-image has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:42.8571%\"><\/div><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/CABECERA-5-1024x538.png\" class=\"attachment-large size-large\" alt=\"CABECERA 5\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-image has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:42.8571%\"><\/div><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/CABECERA-3-1024x538.png\" class=\"attachment-large size-large\" alt=\"CABECERA 3\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><div class=\"w-vwrapper us_custom_40e8c6d0 align_none valign_top\"><div class=\"w-image us_custom_75faae3d align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"618\" height=\"358\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/32.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/32.png 618w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/32-300x174.png 300w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/div><\/div>[vc_custom_heading text=&#8221;Landelijk hotel Tenerife&#8221; font_container=&#8221;tag:h1|text_align:left&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h1&#8243; el_class=&#8221;hero-title&#8221; css=&#8221;%7B%22default%22%3A%7B%22color%22%3A%22_header_middle_bg%22%2C%22font-size%22%3A%2220px%22%2C%22font-weight%22%3A%22600%22%7D%7D&#8221;][vc_custom_heading text=&#8221;HOTEL CASA JUSTA&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h1&#8243; el_class=&#8221;hero-title&#8221; css=&#8221;%7B%22default%22%3A%7B%22color%22%3A%22_header_middle_bg%22%2C%22font-size%22%3A%2260px%22%2C%22font-weight%22%3A%22600%22%7D%2C%22laptops%22%3A%7B%22color%22%3A%22_header_middle_bg%22%2C%22font-size%22%3A%2260px%22%2C%22font-weight%22%3A%22600%22%7D%2C%22tablets%22%3A%7B%22color%22%3A%22_header_middle_bg%22%2C%22font-size%22%3A%2260px%22%2C%22font-weight%22%3A%22600%22%7D%2C%22mobiles%22%3A%7B%22color%22%3A%22_header_middle_bg%22%2C%22font-size%22%3A%2240px%22%2C%22font-weight%22%3A%22600%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_86c2f31d hero-subtitle has_text_color\"><div class=\"wpb_wrapper\"><p>In het hart van Tenerife, een iconisch hotel met meer dan 225 jaar geschiedenis.<br \/>\nEen intiem toevluchtsoord waar traditie, natuur en comfort samenkomen om u<br \/>\neen onvergetelijke ervaring op Tenerife te bezorgen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_94be0cb5 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_10377d2d\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Welkom bij Casa Justa<br \/>\n, een iconisch hotel op Tenerife&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.8rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_069b8f1c\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Dompel uzelf onder in de rust van Tegueste, een plek omgeven door wijngaarden en natuur. In ons <strong>landelijk hotel op Tenerife<\/strong> vindt u de perfecte balans tussen geschiedenis, rust en modern comfort, om te ontsnappen aan het massatoerisme en de authentieke essentie van Tenerife te beleven. <\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_2 us_custom_703b2333\" href=\"#reserva\"><span class=\"w-btn-label\">NU RESERVEREN<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_e6b302da\"><div class=\"wpb_wrapper\"><div class=\"w-slider style_none fit_cover nav_none count_3\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1031\" data-rsh=\"755\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/11.png\"><span data-alt=\"patio\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1031\" data-rsh=\"755\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/12.png\"><span data-alt=\"vistas\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"1852\" data-rsh=\"1181\" href=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-33.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/11.png\" width=\"1031\" height=\"755\" alt=\"patio\" loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:false,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:1031,&quot;autoScaleSliderHeight&quot;:755}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1621c224 estancias height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Ontdek onze verblijven&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-top%22%3A%221rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"g-cols wpb_row us_custom_6d149020 via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-grid carousel-rooms type_carousel layout_326 items_3\" id=\"us_grid_1\" style=\"--items:3;--gap:0.5rem;\"><style>.layout_326 .w-grid-item-h{}.layout_326 .usg_vwrapper_2{padding-left:1.5rem!important;padding-right:1.5rem!important}.layout_326 .usg_text_1{color:var(--color-header-transparent-text-hover)!important}<\/style><div class=\"w-grid-list owl-carousel valign_stretch dotstyle_circle navstyle_3 navpos_outside owl-responsive-2000 center_item with_arrows\" style=\"--transition-duration:350ms;--arrows-size:2rem;\">\t<article class=\"w-grid-item post-3098 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3098\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago\/\" aria-label=\"Suite 5 \u2013 El Drago\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-57-1024x686.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago\/\">Suite 5 \u2013 El Drago<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Kracht, levensduur en natuur&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Ge\u00efnspireerd door de iconische Canarische boom, is deze kamer een viering van het leven en de sereniteit. Ruim en licht, met uitzicht&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3099 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3099\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel\/\" aria-label=\"Suite 6 \u2013 El Laurel\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-65-1024x676.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel\/\">Suite 6 \u2013 El Laurel<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Traditie en sereniteit in zijn puurste vorm&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]De naam doet denken aan de laurierbossen in het noorden van Tenerife, en het interieur straalt dezelfde frisheid en&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3100 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3100\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina\/\" aria-label=\"Suite 4 \u2013 La Sabina\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"639\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-49-1024x639.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina\/\">Suite 4 \u2013 La Sabina<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;De wijntraditie gemaakt om te rusten&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Met knipoogjes naar de wijngeschiedenis van Tegueste combineert dit verblijf de rustieke esthetiek met een vleugje modern design. Donkerhouten meubilair,&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3158 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3158\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-1-la-vina\/\" aria-label=\"Suite 1 \u2013 La Vi\u00f1a\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"669\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/01\/HotelCasaJusta-Tenerife-6-1-1024x669.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-1-la-vina\/\">Suite 1 \u2013 La Vi\u00f1a<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;De essentie van het Canarische landschap &#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Ge\u00efnspireerd door de wijngaarden rondom Tegueste, combineert dit verblijf de frisheid van natuurlijke tinten met de charme van hout.&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-1-la-vina\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3168 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3168\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-2-los-alisios\/\" aria-label=\"Suite 2 \u2013 Los Alisios\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-26-1024x705.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-2-los-alisios\/\">Suite 2 \u2013 Los Alisios<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Licht en geschiedenis onder \u00e9\u00e9n dak&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Deze kamer, gelegen naast de centrale patio, weerspiegelt de traditionele ziel van het huis: hoge plafonds, zichtbare stenen en een&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-2-los-alisios\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3179 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3179\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago-2\/\" aria-label=\"Suite 5 \u2013 El Drago\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-57-1024x686.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago-2\/\">Suite 5 \u2013 El Drago<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Kracht, levensduur en natuur&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Ge\u00efnspireerd door de iconische Canarische boom, is deze kamer een viering van het leven en de sereniteit. Ruim en licht, met uitzicht&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-5-el-drago-2\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3182 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3182\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel-2\/\" aria-label=\"Suite 6 \u2013 El Laurel\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-65-1024x676.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel-2\/\">Suite 6 \u2013 El Laurel<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Traditie en sereniteit in zijn puurste vorm&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]De naam doet denken aan de laurierbossen in het noorden van Tenerife, en het interieur straalt dezelfde frisheid en&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-6-el-laurel-2\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3186 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3186\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina-2\/\" aria-label=\"Suite 4 \u2013 La Sabina\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"639\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-49-1024x639.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina-2\/\">Suite 4 \u2013 La Sabina<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;De wijntraditie gemaakt om te rusten&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]Met knipoogjes naar de wijngeschiedenis van Tegueste combineert dit verblijf de rustieke esthetiek met een vleugje modern design. Donkerhouten meubilair,&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-4-la-sabina-2\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-3189 suites type-suites status-publish has-post-thumbnail hentry\" data-id=\"3189\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 wrapper-rooms align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 has_ratio\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-3-la-laja\/\" aria-label=\"Suite 3 \u2013 La Laja\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"700\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-38-1024x700.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a><div style=\"padding-bottom:100%\"><\/div><\/div><div class=\"w-vwrapper usg_vwrapper_2 wrapper-text-rooms align_none valign_top\"><p class=\"w-post-elm post_title usg_post_title_1 title-rooms entry-title color_link_inherit\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-3-la-laja\/\">Suite 3 \u2013 La Laja<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">[vc_custom_heading text=&#8221;Waar steen en stilte elkaar ontmoeten&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]De naam \u201cLaja\u201d is een eerbetoon aan het vulkanische gesteente dat het Canarische architectuur karakter geeft. Dit verblijf biedt een&hellip;<\/div><div class=\"w-text usg_text_1 button-rooms has_text_color\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/suites\/suite-3-la-laja\/\" class=\"w-text-h\"><span class=\"w-text-value\">Saber m\u00e1s<\/span><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t<\/article>\n<\/div>\t<div class=\"g-preloader type_1\">\n\t\t<div><\/div>\n\t<\/div>\n\t\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;none&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;326&quot;,&quot;items_offset&quot;:&quot;0px&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22url%22%3A%22%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;suites&quot;],&quot;post_status&quot;:[&quot;publish&quot;,&quot;acf-disabled&quot;],&quot;posts_per_page&quot;:999},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;menu_order&quot;:&quot;DESC&quot;},&quot;order&quot;:&quot;DESC&quot;},&quot;type&quot;:&quot;carousel&quot;,&quot;us_grid_post_type&quot;:&quot;suites&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:1,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;nl&quot;},&quot;carousel_settings&quot;:{&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Previous&quot;,&quot;next&quot;:&quot;Volgende&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:3000,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:0,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;651&quot;:{&quot;items&quot;:3,&quot;autoplay&quot;:false,&quot;center&quot;:true,&quot;dots&quot;:false,&quot;nav&quot;:true,&quot;autoHeight&quot;:false,&quot;autoWidth&quot;:false,&quot;loop&quot;:true,&quot;stagePadding&quot;:0}}}}'><\/div>\n\t<\/div><\/div><\/div><\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_4 us_custom_b08249a5\" href=\"#\"><span class=\"w-btn-label\">ONTDEK ALLE KAMERS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_24941e40 height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Diensten van hotel casa justa&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-top%22%3A%221rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"g-cols wpb_row us_custom_6d149020 via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_78203f0a cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/1.png\" class=\"attachment-full size-full\" alt=\"wifi\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Gratis wifi in<br \/>\nalle ruimtes<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/2.png\" class=\"attachment-full size-full\" alt=\"limpieza\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Schoonmaak<br \/>\nservice inbegrepen<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/3.png\" class=\"attachment-full size-full\" alt=\"piscina\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Zwembad<br \/>\nin de openlucht<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4.png\" class=\"attachment-full size-full\" alt=\"info\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Toerisme en routes<br \/>\naanbevolen<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_d28f4cd7 cajavalores iconpos_top style_default color_primary align_center no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:3rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/5.png\" class=\"attachment-full size-full\" alt=\"parking\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><h3 style=\"text-align: center;\">Priv\u00e9parkeerplaats op het terrein<\/h3>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_866ea448 experiencia-unica height_auto full_height valign_center width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container stretched\"><div class=\"vc_column-inner us_custom_f618d1b7\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1149\" height=\"826\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-5.png\" class=\"attachment-full size-full\" alt=\"vistas\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-5.png 1149w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-5-300x216.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-5-1024x736.png 1024w\" sizes=\"auto, (max-width: 1149px) 100vw, 1149px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_abc85520\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Geniet van een<br \/>\nunieke ervaring<br \/>\nop Tenerife&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"w-tabs us_custom_3ce9c5dd style_default switch_click accordion\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"cfb5\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-cfb5\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">STRANDEN EN KUST IN DE BUURT<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content us_custom_71d3e3d1\" id=\"content-cfb5\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Bajamar en Punta del Hidalgo:<\/strong> Geniet van wandelingen langs<br \/>\nde zee en ontspanning in een natuurlijke omgeving.<br \/>\n<strong>Natuurlijke zwembaden in het noorden van Tenerife:<\/strong> Baden in<br \/>\nvulkanische zwembaden omgeven door unieke landschappen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"e1d6\"><button class=\"w-tabs-section-header\" aria-controls=\"content-e1d6\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">NATUUR EN WANDELEN<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-e1d6\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Barranco de Tegueste:<\/strong> Wandel over oude stenen paden tussen wijngaarden en laurierbossen. Perfect om in contact te komen met de natuur en te genieten van een uniek uitzicht.<br \/>\n<strong>Camino del Drago:<\/strong> Korte wandeling naar de iconische Canarische drakenbomen, symbolen van kracht en een lang leven op Tenerife.<br \/>\n<strong>Parque Rural de Anaga:<\/strong> Waag u op bergroutes en door eeuwenoude bossen, met uitzicht op de Atlantische Oceaan.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"x3b2\"><button class=\"w-tabs-section-header\" aria-controls=\"content-x3b2\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">LOKALE GASTRONOMIE<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-x3b2\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Kaasmakerijen en wijnkelders:<\/strong> Proef de beste Canarische kazen en<br \/>\nwijnen uit de regio.<br \/>\n<strong>Wekelijkse markt van Tegueste:<\/strong> Verse producten, ambachten en het authentieke lokale leven.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"u583\"><button class=\"w-tabs-section-header\" aria-controls=\"content-u583\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">GESCHIEDENIS EN CULTUUR<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-u583\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Casa de los Marqueses de Tegueste:<\/strong> Ontdek de architectuur en de geschiedenis van de regio vanaf de 18e eeuw.<br \/>\n<strong>Iglesia de San Marcos:<\/strong> Bezoek een van de meest iconische historische monumenten van Tegueste.<br \/>\n<strong>Routes langs wijnkelders en wijngaarden:<\/strong> Verken de lokale wijntraditie en proef typische wijnen van Tenerife.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row testimonios height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Beoordelingen van gasten van het<br \/>\nlandelijk hotel casa justa&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%22-6rem%22%7D%7D&#8221;]<div class=\"w-html\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-content-align-center\" data-no-translation=\"true\" data-layout-id=\"36\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKVEV9RoCRcb-i5sIH74ndfPbdoBpv296b2wzvrn8Up-Lj0CA=w64-h64-c-rp-mo-br100\" alt=\"Jesus Mar\u00eda Mach\u00edn profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jesus Mar\u00eda Mach\u00edn <\/div> <div class=\"ti-date\">03\/12\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->casa Do\u00f1aJusta, tremendo y excelente alojamiento rural,,!,? Casa con todas las comodidades a d\u00eda de hoy, unas paredes cargadas de historia , exquisita restauraci\u00f3n y adaptaci\u00f3n a los nuevos tiempos y su funcionalidad como hotel rural,..buen\u00edsima energ\u00eda en todo el entorno, ideal para el descanso . Andando muy muy cerca, el centro  del pueblo de Tegueste, donde est\u00e1 ubicada,.\nTegueste, peque\u00f1o gran pueblo al norte de Tenerife, a mi modo de ver desconocido e infravalorado por muchos..que lo tiene todo., comercios de todo tipo,  buen\u00edsima y variada hosteler\u00eda , mercadillo agr\u00edcola los fines de semana, con variedad de productos locales de cercan\u00eda y gran calidad , menci\u00f3n especial a las carnicer\u00edas del pueblo, con la hist\u00f3rica Carnicer\u00eda Florencio, y el maestro Tito al frente de case cien a\u00f1os de tradici\u00f3n familiar ..las mejores carnes del pa\u00eds (Canarias ) est\u00e1n aqu\u00ed..y muy buenos precios.\nMultitud de interesantes rutas para caminar desde el propio pueblo o desde puntos cercanos \u2026parques rurales \u2026 costa..\nAdem\u00e1s\u2026.a tan s\u00f3lo 15 minutos de la Laguna hist\u00f3rica,, lo cual  abre el abanico  de posibilidades ,de ocio gastron\u00f3micas,comerciales y culturales \u2026de forma infinita.\nEn fin que me gusta Tegueste ,, y que en esta casa estamos a gust\u00edsimo  cada vez que vamos .<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKpJMXA1WvGG43Pqb7cbP5lVN7GeO6JEd-tGbjBvA5IlDD0lc8=w64-h64-c-rp-mo-br100\" alt=\"Eztizen Gonz\u00e1lez Sagarduy profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Eztizen Gonz\u00e1lez Sagarduy <\/div> <div class=\"ti-date\">19\/09\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Estuvimos en Casa Justa hace unas semanas y la experiencia fue excelente. Es un espacio muy tranquilo y acogedor,  perfecto para desconectar y descansar. Desde el proceso de reserva hasta la estancia, la atenci\u00f3n de Peli fue inmejorable. Sin duda, un lugar muy recomendable.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV21hPYO1kQ8kxMkuDaO3t7u8mP0i5LyVDJttCrrq2ei0zWDQLhmg=w64-h64-c-rp-mo-ba4-br100\" alt=\"Carlos A. Armas Su\u00e1rez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Carlos A. Armas Su\u00e1rez <\/div> <div class=\"ti-date\">22\/08\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Buen sitio para hacer una escapada de fin de semana o hacer unas vacaciones. Sitio super tranquilo, no s\u00e9 oye nada y te despiertan los p\u00e1jaros por la ma\u00f1ana.. De diez..<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXZgnFWqWOz_my8AIxcj4EIsJ69uIK_OyMEVcjReo1pMWX-sPf9=w64-h64-c-rp-mo-ba3-br100\" alt=\"Simon Cooper profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Simon Cooper <\/div> <div class=\"ti-date\">29\/01\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Wonderful flat in a gorgeous house with grounds. Superb bed and facilities plus lovely sitting out area with pool and views. Quiet location  short walk from the centre of town. Would love to come and stay again<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVZ7KPiAN7kbMo0-Z5QryKwP_nB3439z-eknT7iN5iaQu8Q7vA=w64-h64-c-rp-mo-ba4-br100\" alt=\"Pavel Konrad profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Pavel Konrad <\/div> <div class=\"ti-date\">19\/01\/2025<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Einfach, aber zauberhaft.\nGute Restaurants in der N\u00e4he.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLD0WF902Bok-Ja5GGl6fNhP-Q4X054vDBzXMm6JdnuG5Ow0g=w64-h64-c-rp-mo-ba4-br100\" alt=\"emma Cabello profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> emma Cabello <\/div> <div class=\"ti-date\">11\/10\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Un gran lugar, tranquilo, buen trato, recomendado<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVhQgriKNd1ny4vgWlapLKbDtxAQTUvH5IaozZVnnRrLUSt6B04=w64-h64-c-rp-mo-ba2-br100\" alt=\"Josef Schartner profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Josef Schartner <\/div> <div class=\"ti-date\">18\/05\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Kleine, nette Anlage mit super m\u00f6glichkeiten f\u00fcr die Freizeit. Unsere Wohnung war au\u00dfergew\u00f6hnlich eingerichtet und sehr sch\u00f6n und gro\u00df. Wenn, dann wieder hier. Tugueste hat auch gut gefallen, waren 6 N\u00e4chte dort.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXHzAvL01Sgd-Bcuuj43wkWgfzc6ru2Vk3RC5WGhBwfuXCCQJs=w64-h64-c-rp-mo-ba4-br100\" alt=\"Louise Bankhead profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Louise Bankhead <\/div> <div class=\"ti-date\">20\/04\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Beautiful place with a lot of character. Very well situated.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL1X3h9s6MKRiWTxDepUTqUNkOaIuFXWdhpS33ovQDM2Y76mw=w64-h64-c-rp-mo-br100\" alt=\"Juan Antonio profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Juan Antonio <\/div> <div class=\"ti-date\">07\/04\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Sitio muy bonito y muy limpio. Trato agradable de todos,  Peli, Marisol y Pedro. Gracias, volveremos pronto.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"1\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVFcCg6Q6dBhT9g5VjRFLiU62GGGhtOQ49BzCK5xX_ns_kgmFwWxg=w64-h64-c-rp-mo-br100\" alt=\"Nuria Guti\u00e9rrez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Nuria Guti\u00e9rrez <\/div> <div class=\"ti-date\">17\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>    <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/trustindex-google-widget.css?1765895602\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_1f3d19ce height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Buitenzones van casa justa&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-top%22%3A%221rem%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-content-carousel items_3\"><div class=\"owl-carousel valign_stretch dotstyle_circle navstyle_3 navpos_outside owl-responsive-2000 with_arrows\" style=\"--items-gap:30px;--transition-duration:350ms;--arrows-size:1.5rem;\" onclick=\"return {&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Previous&quot;,&quot;next&quot;:&quot;Volgende&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:3000,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:30,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;651&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:3,&quot;loop&quot;:false,&quot;nav&quot;:true,&quot;stagePadding&quot;:0}}}\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"653\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-33-1024x653.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-33-1024x653.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-33-300x191.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-33.jpg 1852w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"657\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-123-1024x657.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-123-1024x657.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-123-300x192.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-123.jpg 1842w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"719\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-120-1024x719.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-120-1024x719.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-120-300x211.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-120.jpg 1683w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"629\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-113-scaled-1024x629.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-113-scaled-1024x629.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-113-scaled-300x184.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-113-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-109-scaled-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-109-scaled-1024x576.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-109-scaled-300x169.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-109-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"725\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-92-1024x725.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-92-1024x725.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-92-300x213.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-92.jpg 1667w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"587\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-2-scaled-1024x587.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-2-scaled-1024x587.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-2-scaled-300x172.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-2-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-86-1024x676.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-86-1024x676.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-86-300x198.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-86.jpg 1788w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"688\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-105-1024x688.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-105-1024x688.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-105-300x202.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-105.jpg 1757w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"590\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-79-scaled-1024x590.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-79-scaled-1024x590.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-79-scaled-300x173.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-79-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-106-scaled-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-106-scaled-1024x576.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-106-scaled-300x169.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-106-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-15-1024x666.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-15-1024x666.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-15-300x195.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-15.jpg 1817w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-RSFOTO.ES_-scaled-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-RSFOTO.ES_-scaled-1024x576.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-RSFOTO.ES_-scaled-300x169.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-RSFOTO.ES_-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"601\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-97-scaled-1024x601.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-97-scaled-1024x601.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-97-scaled-300x176.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-97-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"647\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-35-1024x647.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-35-1024x647.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-35-300x190.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-35.jpg 1869w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-75-scaled-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-75-scaled-1024x576.jpg 1024w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-75-scaled-300x169.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/11\/HotelCasaJusta-Tenerife-75-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_3cbf8d23 blog-section height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Mis onze blog niet&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%220%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<\/div><\/div><\/div><div class=\"vc_col-sm-9 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-grid type_carousel layout_240 items_3\" id=\"us_grid_2\" style=\"--items:3;--gap:1rem;\"><style>.layout_240 .w-grid-item-h{}.layout_240 .usg_vwrapper_1{background:var(--color-header-transparent-text)!important}.layout_240 .usg_post_title_1{color:var(--color-header-middle-text)!important;padding-left:2rem!important;padding-top:1rem!important;padding-right:2rem!important}.layout_240 .usg_post_content_1{padding-left:2rem!important;padding-right:2rem!important}.layout_240 .usg_post_date_1{padding-left:2rem!important;padding-bottom:1.5rem!important}<\/style><div class=\"w-grid-list owl-carousel valign_stretch dotstyle_circle navstyle_3 navpos_outside owl-responsive-2000 with_arrows\" style=\"--transition-duration:350ms;--arrows-size:3rem;\">\t<article class=\"w-grid-item post-3019 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"3019\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/top-10-plekken-om-te-eten-in-noord-tenerife\/\" aria-label=\"Top 10 plekken om te eten in Noord-Tenerife\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/01\/donde-comer-en-tenerife-norte-300x188.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/01\/donde-comer-en-tenerife-norte-300x188.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/01\/donde-comer-en-tenerife-norte.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/top-10-plekken-om-te-eten-in-noord-tenerife\/\">Top 10 plekken om te eten in Noord-Tenerife<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Top 10 plekken om te eten in Noord-Tenerife Als je een uitstapje aan het organiseren bent en je afvraagt waar je kunt eten in Noord-Tenerife, dan ben je hier aan&hellip;<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2026-01-16T13:27:09+02:00\" title=\"16 januari 2026 om 13:27:09 +02:00\">8 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-2530 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"2530\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/wat-te-doen-in-tenerife-noord\/\" aria-label=\"Wat te doen in Tenerife-Noord?\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/que-hacer-en-tenerife-norte-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"wat te doen in Tenerife-Noord\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/que-hacer-en-tenerife-norte-300x169.jpg 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/12\/que-hacer-en-tenerife-norte.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/wat-te-doen-in-tenerife-noord\/\">Wat te doen in Tenerife-Noord?<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Wat te doen in Tenerife-Noord? Weet je niet wat te doen in Tenerife-Noord? Op deze prachtige plek kun je genieten van unieke groene landschappen, dorpen met geschiedenis, vulkanische stranden, natuurlijke&hellip;<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2025-12-16T16:18:27+02:00\" title=\"16 december 2025 om 16:18:27 +02:00\">9 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-2520 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"2520\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/wijnen-van-tenerife-een-ervaring-voor-de-zintuigen\/\" aria-label=\"Wijnen van Tenerife: een ervaring voor de zintuigen\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Mask-group-300x130.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Mask-group-300x130.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Mask-group.png 497w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/wijnen-van-tenerife-een-ervaring-voor-de-zintuigen\/\">Wijnen van Tenerife: een ervaring voor de zintuigen<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Rondleidingen door wijnkelders, wijnproeverijen en tips voor liefhebbers van wijntoerisme in het noorden van Tenerife.<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2025-10-21T13:56:00+02:00\" title=\"21 oktober 2025 om 13:56:00 +02:00\">11 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-2621 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"2621\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/200-jaar-geschiedenis-in-casa-justa\/\" aria-label=\"200 jaar geschiedenis in Casa Justa\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"136\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8-300x136.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8-300x136.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png 497w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/200-jaar-geschiedenis-in-casa-justa\/\">200 jaar geschiedenis in Casa Justa<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Ontdek hoe dit emblematische huis in Tegueste de tand des tijds heeft doorstaan en is getransformeerd in een boetiekverblijf. Verhalen over de vroegere bewoners, architectonische curiositeiten en hoe we de&hellip;<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2025-10-08T12:56:56+02:00\" title=\"8 oktober 2025 om 12:56:56 +02:00\">11 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-2593 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"2593\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/canarische-gastronomie-smaken-die-u-niet-mag-missen\/\" aria-label=\"Canarische gastronomie: smaken die u niet mag missen\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"132\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-9-300x132.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-9-300x132.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-9.png 497w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/canarische-gastronomie-smaken-die-u-niet-mag-missen\/\">Canarische gastronomie: smaken die u niet mag missen<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Aanbevelingen voor gerechten, lokale producten en restaurants in de buurt. Van traditionele tapas tot gastronomische ervaringen, met tips om tijdens uw verblijf te genieten van de authentieke keuken van Tenerife.<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2025-10-07T15:36:32+02:00\" title=\"7 oktober 2025 om 15:36:32 +02:00\">11 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n\t<article class=\"w-grid-item post-2563 post type-post status-publish format-standard has-post-thumbnail hentry category-ongecategoriseerd\" data-id=\"2563\">\n\t\t<div class=\"w-grid-item-h\">\n\t\t\t\t\t\t<div class=\"w-vwrapper usg_vwrapper_1 align_none valign_top\"><div class=\"w-post-elm post_image usg_post_image_1 stretched\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/routes-en-geheimen-van-tegueste-en-het-noorden-van-tenerife\/\" aria-label=\"Routes en geheimen van Tegueste en het noorden van Tenerife\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-10-300x130.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-10-300x130.png 300w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-10.png 497w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><p class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title\"><a href=\"https:\/\/www.hotelcasajusta.com\/nl\/routes-en-geheimen-van-tegueste-en-het-noorden-van-tenerife\/\">Routes en geheimen van Tegueste en het noorden van Tenerife<\/a><\/p><div class=\"w-post-elm post_content usg_post_content_1\">Routes en geheimen van Tegueste en het noorden van Tenerife Een praktische gids voor liefhebbers van wandelen, wijntoerisme en lokale cultuur. Inclusief routes tussen wijngaarden, bezoeken aan wijnkelders, uitkijkpunten en&hellip;<\/div><time class=\"w-post-elm post_date usg_post_date_1 entry-date published\" datetime=\"2025-10-07T15:35:53+02:00\" title=\"7 oktober 2025 om 15:35:53 +02:00\">11 maanden geleden<\/time><\/div>\t\t<\/div>\n\t\t\t<\/article>\n<\/div>\t<div class=\"g-preloader type_1\">\n\t\t<div><\/div>\n\t<\/div>\n\t\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;none&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;medium&quot;,&quot;ignore_items_size&quot;:&quot;1&quot;,&quot;items_layout&quot;:&quot;240&quot;,&quot;items_offset&quot;:&quot;0px&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22url%22%3A%22%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;post&quot;],&quot;post_status&quot;:[&quot;publish&quot;,&quot;acf-disabled&quot;],&quot;posts_per_page&quot;:&quot;10&quot;},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;date&quot;:&quot;DESC&quot;}},&quot;type&quot;:&quot;carousel&quot;,&quot;us_grid_post_type&quot;:&quot;post&quot;,&quot;us_grid_ajax_index&quot;:2,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:2,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;nl&quot;},&quot;carousel_settings&quot;:{&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Previous&quot;,&quot;next&quot;:&quot;Volgende&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:3000,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:0,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;651&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;items&quot;:2,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;1025&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;items&quot;:2,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;1281&quot;:{&quot;items&quot;:3,&quot;autoplay&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;nav&quot;:true,&quot;autoHeight&quot;:false,&quot;autoWidth&quot;:false,&quot;loop&quot;:true,&quot;stagePadding&quot;:0}}}}'><\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row faq-section height_large width_custom\" style=\"--site-content-width:1000px;\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Veelgestelde vragen over ons landelijk hotel in het noorden van Tenerife&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%220%22%7D%2C%22laptops%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%221.5rem%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22tablets%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%2C%22mobiles%22%3A%7B%22text-align%22%3A%22center%22%2C%22font-size%22%3A%22%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%7D%7D&#8221;]<div class=\"w-tabs us_custom_71d3e3d1 style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"b175\"><button class=\"w-tabs-section-header\" aria-controls=\"content-b175\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke soorten verblijven biedt Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content us_custom_25ce5a41\" id=\"content-b175\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Wij bieden ruime en gezellige kamers in een traditionele Canarische stijl, uitgerust met alle nodige voorzieningen voor een ontspannen verblijf. We hebben tweepersoonskamers, familiekamers en suites met uitzicht op de natuurlijke omgeving.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"a29d\"><button class=\"w-tabs-section-header\" aria-controls=\"content-a29d\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is het toegestaan om te koken in ons landelijk hotel op Tenerife?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-a29d\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Sommige van onze kamers en appartementen hebben een keuken die is uitgerust voor priv\u00e9gebruik. Als er geen keuken aanwezig is, bieden we toegang tot gemeenschappelijke ruimtes waar u basisvoedsel kunt bereiden.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"t3b7\"><button class=\"w-tabs-section-header\" aria-controls=\"content-t3b7\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is Casa Do\u00f1a Justa geschikt voor gezinnen?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-t3b7\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja. Onze accommodatie is perfect voor gezinnen die op zoek zijn naar rust en natuur. We hebben familiekamers, grote buitenruimtes en activiteiten in de buurt die ideaal zijn voor kinderen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"r4c7\"><button class=\"w-tabs-section-header\" aria-controls=\"content-r4c7\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Zijn huisdieren toegestaan?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-r4c7\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Nee, het spijt ons, huisdieren zijn niet toegestaan in onze faciliteiten. Dit beleid helpt ons om een rustige en geschikte omgeving voor al onze gasten te behouden.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"f5f2\"><button class=\"w-tabs-section-header\" aria-controls=\"content-f5f2\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Wat is het in- en uitcheckbeleid?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-f5f2\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Inchecken kan vanaf 15:00 uur en uitchecken tot 11:00 uur. Als u andere tijden nodig heeft, neem dan contact met ons op en we zullen ons best doen om ons aan te passen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"l73e\"><button class=\"w-tabs-section-header\" aria-controls=\"content-l73e\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Is er parkeergelegenheid beschikbaar?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-l73e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja, we hebben gratis priv\u00e9parkeergelegenheid voor gasten, afhankelijk van beschikbaarheid. Het is ook mogelijk om gemakkelijk te parkeren in de directe omgeving van het etablissement.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"o8bc\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o8bc\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke extra diensten biedt Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o8bc\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Onze diensten omvatten:<\/p>\n<p>Ontbijt met lokale producten<\/p>\n<p>Gratis wifi in alle faciliteiten<\/p>\n<p>Terras en tuinen<\/p>\n<p>Schoonmaakservice<\/p>\n<p>Toeristische informatie en activiteitenbeheer<\/p>\n<p>Transfers op aanvraag (tegen extra kosten)<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"ga3d\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ga3d\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Welke activiteiten zijn er in de buurt te doen?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ga3d\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>De locatie is ideaal om te genieten van de natuur en cultuur van Tenerife. In de buurt kunt u: <\/p>\n<p>Wandelroutes<\/p>\n<p>Sterren kijken<\/p>\n<p>Avontuurlijke sporten<\/p>\n<p>Stranden en natuurlijke zwembaden<\/p>\n<p>Bezoeken aan traditionele dorpen en ambachtelijke markten<\/p>\n<p>Bezoeken aan lokale wijnkelders<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"hb68\"><button class=\"w-tabs-section-header\" aria-controls=\"content-hb68\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Hoe kom ik bij Casa Do\u00f1a Justa?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-hb68\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>We zijn gevestigd in een landelijk gebied dat goed verbonden is met de belangrijkste wegen van het eiland. Na de reservering ontvangt u gedetailleerde instructies en GPS-co\u00f6rdinaten. We kunnen u ook helpen bij het organiseren van transfers vanaf de luchthaven.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"uc7a\"><button class=\"w-tabs-section-header\" aria-controls=\"content-uc7a\" aria-expanded=\"false\"><p class=\"w-tabs-section-title\">Kunnen reserveringen rechtstreeks op de website worden gemaakt?<\/p><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-uc7a\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ja, u kunt gemakkelijk en met de beste prijsgarantie reserveren via onze offici\u00eble website. Het proces is eenvoudig, veilig en u kunt de beschikbaarheid in realtime raadplegen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_057801f8 contacto height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Neem contact met<br \/>\nons op&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; google_fonts=&#8221;font_family:Raleway%3A100%2C200%2C300%2Cregular%2C500%2C600%2C700%2C800%2C900|font_style:400%20regular%3A400%3Anormal&#8221; tag_name=&#8221;h2&#8243; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22left%22%2C%22font-weight%22%3A%22500%22%2C%22text-transform%22%3A%22uppercase%22%2C%22margin-left%22%3A%220%22%7D%7D&#8221;]<div class=\"w-iconbox iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"19\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/1a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p>Calle Astrof\u00edsico P\u00e9rez \u00c1lvarez Mart\u00edn,<br \/>\nn\u00ba24 38280 Tegueste, Santa Cruz de Tenerife<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"19\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/2a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoicVpNNUM3ZVkya1ZjMVFFWUxFMzliSiIsInBhc3RlSUQiOjE4NDY1OTA0MzIsImRhdGFUeXBlIjoic2NlbmUifQo=(\/figmeta)--&gt;\"><\/span>+34 626 821 926<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"17\" height=\"13\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/3a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoicVpNNUM3ZVkya1ZjMVFFWUxFMzliSiIsInBhc3RlSUQiOjE4NDY1OTA0MzIsImRhdGFUeXBlIjoic2NlbmUifQo=(\/figmeta)--&gt;\"><\/span>info@hotelcasajusta.com<\/p>\n<\/div><\/div><\/div><div class=\"w-iconbox us_custom_703b2333 iconpos_left style_default color_primary align_left no_title icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:1rem;\"><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4a.png\" class=\"attachment-full size-full\" alt=\"icons\" \/><\/div><div class=\"w-iconbox-meta\"><div class=\"w-iconbox-text\"><p>Openingstijden:<br \/>\nMaandag tot zondag: 09:00 \u2013 20:00<\/p>\n<\/div><\/div><\/div><div class=\"w-image us_custom_703b2333 align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"671\" height=\"228\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007.png\" class=\"attachment-full size-full\" alt=\"map\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007.png 671w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-07-150007-300x102.png 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2692-o1\" lang=\"nl-NL\" dir=\"ltr\" data-wpcf7-id=\"2692\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/1887#wpcf7-f2692-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2692\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"nl_NL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2692-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<label for=\"nombre\"> Uw naam *\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"nombre\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span> <\/label>\n\n<label for=\"email\"> Uw e-mailadres *\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label>\n\n<label for=\"telefono\"> Uw telefoonnummer *\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" id=\"telefono\" autocomplete=\"tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span> <\/label>\n\n<label for=\"mensaje\"> Uw bericht\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" id=\"mensaje\" aria-invalid=\"false\" name=\"mensaje\"><\/textarea><\/span> <\/label>\n\n<label for=\"aceptacion\"><span class=\"wpcf7-form-control-wrap\" data-name=\"aceptacion\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"aceptacion\" value=\"1\" id=\"aceptacion\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ik heb het <a rel=\"nofollow\" target=\"_blank\" href=\"\/politica-de-privacidad\/\">privacybeleid<\/a> gelezen en ga ermee akkoord.<\/label>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"form-contact\" type=\"submit\" value=\"Verzenden\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-popup align_none\"><span  class=\"w-popup-trigger type_load\" data-options=\"{&quot;delay&quot;:1}\"><\/span><div class=\"w-popup-overlay\" style=\"background:rgba(0,0,0,0.85);\"><\/div><div class=\"w-popup-wrap layout_right_panel\" role=\"dialog\" aria-modal=\"true\" aria-label=\"PopUp\" style=\"--title-color:var(--color-content-heading);--title-bg-color:var(--color-content-bg-alt);--content-color:var(--color-content-text);--content-bg-color:;--popup-width:537px;\"><div class=\"w-popup-box animation_fadeIn closerpos_inside without_title\"><div class=\"w-popup-box-h\"><button aria-label=\"Sluiten\" class=\"w-popup-closer\" type=\"button\"><\/button><div class=\"w-popup-box-content\"><section class=\"l-section wpb_row us_custom_fe7c2867 height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"537\" height=\"389\" src=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-16.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-16.png 537w, https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-16-300x217.png 300w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_92be0981\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Beste prijs<br \/>\ngegarandeerd bij reservering<br \/>\nvia de offici\u00eble website<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_4 us_custom_703b2333\" href=\"https:\/\/hotel-casa-dona-justa.amenitiz.io\/es\/booking\/room#DatesGuests-BE\"><span class=\"w-btn-label\">RESERVEER VOOR DE BESTE PRIJS<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Routes en geheimen van Tegueste en het noorden van Tenerife Een praktische gids voor liefhebbers van wandelen, wijntoerisme en lokale cultuur. Inclusief routes tussen wijngaarden, bezoeken aan wijnkelders, uitkijkpunten en minder bekende plekjes om Tenerife als een local te beleven.","protected":false},"author":1,"featured_media":3386,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1887","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landelijk hotel op Tenerife | Hotel Casa Justa<\/title>\n<meta name=\"description\" content=\"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelcasajusta.com\/nl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landelijk hotel op Tenerife | Hotel Casa Justa\" \/>\n<meta property=\"og:description\" content=\"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelcasajusta.com\/nl\/\" \/>\n<meta property=\"og:site_name\" content=\"hotelcasajusta\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T10:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"731\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/\",\"name\":\"Landelijk hotel op Tenerife | Hotel Casa Justa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hotel-en-tegueste-casa-justa-e1776937626929.jpg\",\"datePublished\":\"2022-09-30T08:24:42+00:00\",\"dateModified\":\"2025-12-30T10:47:02+00:00\",\"description\":\"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hotel-en-tegueste-casa-justa-e1776937626929.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hotel-en-tegueste-casa-justa-e1776937626929.jpg\",\"width\":966,\"height\":633,\"caption\":\"Hotel en Tegueste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/?page_id=1887\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel Casa Justa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/\",\"name\":\"hotelcasajusta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landelijk hotel op Tenerife | Hotel Casa Justa","description":"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelcasajusta.com\/nl\/","og_locale":"nl_NL","og_type":"article","og_title":"Landelijk hotel op Tenerife | Hotel Casa Justa","og_description":"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.","og_url":"https:\/\/www.hotelcasajusta.com\/nl\/","og_site_name":"hotelcasajusta","article_modified_time":"2025-12-30T10:47:02+00:00","og_image":[{"width":731,"height":602,"url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/4-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"21 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotelcasajusta.com\/nl\/","url":"https:\/\/www.hotelcasajusta.com\/nl\/","name":"Landelijk hotel op Tenerife | Hotel Casa Justa","isPartOf":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/#primaryimage"},"image":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/04\/hotel-en-tegueste-casa-justa-e1776937626929.jpg","datePublished":"2022-09-30T08:24:42+00:00","dateModified":"2025-12-30T10:47:02+00:00","description":"Geniet van Casa Justa, een landelijk hotel op Tenerife, omgeven door natuur, rust en lokale charme. Perfect om te ontspannen.","breadcrumb":{"@id":"https:\/\/www.hotelcasajusta.com\/nl\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelcasajusta.com\/nl\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hotelcasajusta.com\/nl\/#primaryimage","url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/04\/hotel-en-tegueste-casa-justa-e1776937626929.jpg","contentUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2026\/04\/hotel-en-tegueste-casa-justa-e1776937626929.jpg","width":966,"height":633,"caption":"Hotel en Tegueste"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelcasajusta.com\/nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hotelcasajusta.com\/nl\/?page_id=1887"},{"@type":"ListItem","position":2,"name":"Hotel Casa Justa"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelcasajusta.com\/nl\/#website","url":"https:\/\/www.hotelcasajusta.com\/nl\/","name":"hotelcasajusta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelcasajusta.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/1887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/comments?post=1887"}],"version-history":[{"count":4,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/1887\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/pages\/1887\/revisions\/3281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/media\/3386"}],"wp:attachment":[{"href":"https:\/\/www.hotelcasajusta.com\/nl\/wp-json\/wp\/v2\/media?parent=1887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}