{"id":2538,"date":"2025-10-08T12:56:56","date_gmt":"2025-10-08T10:56:56","guid":{"rendered":"https:\/\/www.hotelcasajusta.com\/200-years-of-history-at-casa-justa\/"},"modified":"2026-01-05T15:23:31","modified_gmt":"2026-01-05T13:23:31","slug":"200-years-of-history-at-casa-justa","status":"publish","type":"post","link":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/","title":{"rendered":"200 years of history at Casa Justa"},"content":{"rendered":"<section class=\"l-section wpb_row height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Discover how this emblematic house in Tegueste has stood the test of time and transformed into a boutique retreat. Hear stories of its former residents, learn about its architectural curiosities, and see how we preserve its soul in every corner.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Discover how this emblematic house in Tegueste has stood the test of time and transformed into a boutique retreat. Hear stories of its former residents, learn about its architectural curiosities, and see how we preserve its soul in every corner.","protected":false},"author":1,"featured_media":2539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>200 years of history at Casa Justa - hotelcasajusta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"200 years of history at Casa Justa - hotelcasajusta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/\" \/>\n<meta property=\"og:site_name\" content=\"hotelcasajusta\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-08T10:56:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T13:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"497\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_solbyte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_solbyte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/\"},\"author\":{\"name\":\"admin_solbyte\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/#\\\/schema\\\/person\\\/b088e98ec16e7b8567544de9564df77a\"},\"headline\":\"200 years of history at Casa Justa\",\"datePublished\":\"2025-10-08T10:56:56+00:00\",\"dateModified\":\"2026-01-05T13:23:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/\"},\"wordCount\":60,\"image\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rectangle-8.png\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/\",\"name\":\"200 years of history at Casa Justa - hotelcasajusta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rectangle-8.png\",\"datePublished\":\"2025-10-08T10:56:56+00:00\",\"dateModified\":\"2026-01-05T13:23:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/#\\\/schema\\\/person\\\/b088e98ec16e7b8567544de9564df77a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rectangle-8.png\",\"contentUrl\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Rectangle-8.png\",\"width\":497,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/200-years-of-history-at-casa-justa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"200 years of history at Casa Justa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/\",\"name\":\"hotelcasajusta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hotelcasajusta.com\\\/en\\\/#\\\/schema\\\/person\\\/b088e98ec16e7b8567544de9564df77a\",\"name\":\"admin_solbyte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g\",\"caption\":\"admin_solbyte\"},\"sameAs\":[\"https:\\\/\\\/www.hotelcasajusta.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"200 years of history at Casa Justa - hotelcasajusta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/","og_locale":"en_US","og_type":"article","og_title":"200 years of history at Casa Justa - hotelcasajusta","og_url":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/","og_site_name":"hotelcasajusta","article_published_time":"2025-10-08T10:56:56+00:00","article_modified_time":"2026-01-05T13:23:31+00:00","og_image":[{"width":497,"height":225,"url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png","type":"image\/png"}],"author":"admin_solbyte","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_solbyte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#article","isPartOf":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/"},"author":{"name":"admin_solbyte","@id":"https:\/\/www.hotelcasajusta.com\/en\/#\/schema\/person\/b088e98ec16e7b8567544de9564df77a"},"headline":"200 years of history at Casa Justa","datePublished":"2025-10-08T10:56:56+00:00","dateModified":"2026-01-05T13:23:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/"},"wordCount":60,"image":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/","url":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/","name":"200 years of history at Casa Justa - hotelcasajusta","isPartOf":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#primaryimage"},"image":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png","datePublished":"2025-10-08T10:56:56+00:00","dateModified":"2026-01-05T13:23:31+00:00","author":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/#\/schema\/person\/b088e98ec16e7b8567544de9564df77a"},"breadcrumb":{"@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#primaryimage","url":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png","contentUrl":"https:\/\/www.hotelcasajusta.com\/wp-content\/uploads\/2025\/10\/Rectangle-8.png","width":497,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelcasajusta.com\/en\/200-years-of-history-at-casa-justa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hotelcasajusta.com\/en\/"},{"@type":"ListItem","position":2,"name":"200 years of history at Casa Justa"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelcasajusta.com\/en\/#website","url":"https:\/\/www.hotelcasajusta.com\/en\/","name":"hotelcasajusta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelcasajusta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hotelcasajusta.com\/en\/#\/schema\/person\/b088e98ec16e7b8567544de9564df77a","name":"admin_solbyte","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edd888738bb98bddffbea2c50034264e135aaa1849baae74099aa811d4485252?s=96&d=mm&r=g","caption":"admin_solbyte"},"sameAs":["https:\/\/www.hotelcasajusta.com"]}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/posts\/2538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/comments?post=2538"}],"version-history":[{"count":5,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/posts\/2538\/revisions"}],"predecessor-version":[{"id":2551,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/posts\/2538\/revisions\/2551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/media\/2539"}],"wp:attachment":[{"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/media?parent=2538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/categories?post=2538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hotelcasajusta.com\/en\/wp-json\/wp\/v2\/tags?post=2538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}